{"id":118,"date":"2008-03-03T23:05:21","date_gmt":"2008-03-03T23:05:21","guid":{"rendered":"http:\/\/alejandrozenker.com\/fotografo\/?p=69"},"modified":"2008-03-03T23:05:21","modified_gmt":"2008-03-03T23:05:21","slug":"proyecto-waitman-la-musicalizacion-del-orgasmo-femenino","status":"publish","type":"post","link":"https:\/\/alejandrozenker.com\/blog\/2008\/03\/03\/proyecto-waitman-la-musicalizacion-del-orgasmo-femenino\/","title":{"rendered":"Proyecto WAITMAN: La musicalizaci\u00f3n del orgasmo femenino"},"content":{"rendered":"<p style=\"margin-top: 10px; margin-bottom: 10px;\">Waitman Gobble es el webmaster de la p\u00e1gina de UjENA. Se trata de un sitio espl\u00e9ndido, en el que concurren a la fecha miles de modelos y fot\u00f3grafos de todo el mundo. Hasta ahora, mi relaci\u00f3n con \u00e9l hab\u00eda sido de car\u00e1cter meramente profesional. Sin embargo, algunos comentarios hechos v\u00eda correo electr\u00f3nico referentes a mi deseo de redise\u00f1ar mis sitios personales en la web me hicieron descubrir a todo un personaje. Waitman es, evidentemente, todo un maestro del ciberespacio. Pero ha encontrado en la creaci\u00f3n musical un refugio art\u00edstico. Entre muchas otras cosas ha creado un sitio sui g\u00e9neris: www.explicious.com. All\u00ed invita a las mujeres a enviarle la grabaci\u00f3n de sus orgasmos. De lo que recibe, escoge los m\u00e1s significativos y los musicaliza. Este video que presento a continuaci\u00f3n (y que espero puedas ver, porque por su contenido de desnudo YouTube suele censurarlo como otros que aqu\u00ed se exhiben) conjunta un orgasmo musicalizado por Waitman y fotos que yo tom\u00e9 recientemente en una sesi\u00f3n fotogr\u00e1fica en mi estudio con Ver\u00f3nica como modelo. Espero lo disfruten.<\/p>\n<p style=\"margin-top: 10px; margin-bottom: 10px;\">\n<small><a style=\"text-decoration: underline; color: #888899;\" href=\"http:\/\/avemexico.ning.com\/video\/video\">Encuentra m\u00e1s videos como este en\u00a0<em>Artistas Visuales del Erotismo AVE<\/em><\/a><\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Waitman Gobble es el webmaster de la p\u00e1gina de UjENA. Se trata de un sitio espl\u00e9ndido, en el que concurren a la fecha miles de modelos y fot\u00f3grafos de todo el mundo. Hasta ahora, mi relaci\u00f3n con \u00e9l hab\u00eda sido de car\u00e1cter meramente profesional. Sin embargo, algunos comentarios hechos v\u00eda correo electr\u00f3nico referentes a mi [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10,1],"tags":[],"class_list":["post-118","post","type-post","status-publish","format-standard","hentry","category-fotografo","category-uncategorized"],"aioseo_notices":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/pOdts-1U","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/posts\/118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/comments?post=118"}],"version-history":[{"count":0,"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/posts\/118\/revisions"}],"wp:attachment":[{"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/media?parent=118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/categories?post=118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alejandrozenker.com\/blog\/wp-json\/wp\/v2\/tags?post=118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}